{"id":1340,"date":"2023-09-08T15:54:03","date_gmt":"2023-09-08T21:54:03","guid":{"rendered":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/?p=1340"},"modified":"2023-09-08T15:54:03","modified_gmt":"2023-09-08T21:54:03","slug":"injuve-tamaulipas-lleva-a-cabo-acciones-de-reforestacion-en-la-entidad","status":"publish","type":"post","link":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/2023\/09\/injuve-tamaulipas-lleva-a-cabo-acciones-de-reforestacion-en-la-entidad\/","title":{"rendered":"Injuve Tamaulipas lleva a cabo acciones de reforestaci\u00f3n en la entidad"},"content":{"rendered":"<p style=\"text-align: right;\"><b>\u00a0<\/b><b>Promoviendo una vocaci\u00f3n forestal<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><b>Septiembre 07 de 2023<\/b><\/p>\n<p><b>Cd. Victoria.- <\/b><span style=\"font-weight: 400;\">Comprometidos en fomentar una vocaci\u00f3n forestal encaminada a la protecci\u00f3n y conservaci\u00f3n del medio ambiente, Injuve Tamaulipas bajo la direcci\u00f3n general de Judith Katalyna M\u00e9ndez Cepeda, llev\u00f3 a cabo acciones de reforestaci\u00f3n en distintos municipios de la entidad.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La iniciativa se realiz\u00f3 gracias a la donaci\u00f3n de 800 \u00e1rboles por parte del \u00e1rea de Desarrollo Comunitario del DIF Tamaulipas, en conjunto con la Secretar\u00eda de Desarrollo Urbano y Medio Ambiente (SEDUMA).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Estas acciones forman parte de las jornadas de reforestaci\u00f3n que son apoyadas por los delegados de Injuve y el voluntariado de Misi\u00f3n Tamaulipas, sembrando \u00e1rboles de varias especies en los municipios de D\u00edaz Ordaz, R\u00edo Bravo, San Fernando y Padilla.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La titular del Instituto de la Juventud, Katalyna M\u00e9ndez, coment\u00f3 que \u201cel objetivo principal es hacer conciencia sobre el valor que tiene el entorno natural y la importancia de mantener un habitat saludable, con el fin de garantizar un alto porcentaje de sobrevivencia\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cRefrendando el compromiso con actividades de recuperaci\u00f3n de la vegetaci\u00f3n y cuidado de los recursos naturales, dando cumplimiento a la normatividad ambiental y con la\u00a0firme voluntad del cuidado del medio ambiente del gobernador de Tamaulipas, Am\u00e9rico Villarreal Anaya\u201d, finaliz\u00f3 la funcionaria estatal.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-1342\" src=\"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-content\/uploads\/sites\/19\/2023\/09\/5bb931ec-e338-4294-a57e-9cb6e9f85780.jpg\" alt=\"\" width=\"800\" height=\"600\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-1343\" src=\"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-content\/uploads\/sites\/19\/2023\/09\/ca4fdec0-2709-4505-8283-660482cc392e.jpg\" alt=\"\" width=\"800\" height=\"600\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-1344\" src=\"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-content\/uploads\/sites\/19\/2023\/09\/32a4e276-853c-4f88-82bc-9d9d62122913.jpg\" alt=\"\" width=\"800\" height=\"600\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Promoviendo una vocaci\u00f3n forestal &nbsp; Septiembre 07 de 2023 Cd. Victoria.- Comprometidos en fomentar una vocaci\u00f3n forestal encaminada a la protecci\u00f3n y conservaci\u00f3n del medio\u2026<\/p>\n","protected":false},"author":288,"featured_media":1341,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 03:40:04","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/posts\/1340"}],"collection":[{"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/users\/288"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/comments?post=1340"}],"version-history":[{"count":1,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/posts\/1340\/revisions"}],"predecessor-version":[{"id":1345,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/posts\/1340\/revisions\/1345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/media\/1341"}],"wp:attachment":[{"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/media?parent=1340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/categories?post=1340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/tags?post=1340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}