{"id":1239,"date":"2023-06-28T11:45:15","date_gmt":"2023-06-28T17:45:15","guid":{"rendered":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/?p=1239"},"modified":"2023-06-28T11:45:15","modified_gmt":"2023-06-28T17:45:15","slug":"injuve-apoya-evento-estatal-de-skaters","status":"publish","type":"post","link":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/2023\/06\/injuve-apoya-evento-estatal-de-skaters\/","title":{"rendered":"Injuve apoya evento estatal de Skaters"},"content":{"rendered":"<p style=\"text-align: right;\"><b>Atracci\u00f3n deportiva que reuni\u00f3 a j\u00f3venes de varios municipios de la entidad<\/b><\/p>\n<p><b>Junio 26 de 2023<\/b><\/p>\n<p><b>Ciudad Victoria, Tamaulipas.-<\/b> <span style=\"font-weight: 400;\">Con la intenci\u00f3n de incentivar la participaci\u00f3n de las juventudes, se realiz\u00f3 el evento estatal Tercer Skate Day en Ciudad Victoria con el apoyo del Injuve Tamaulipas, bajo la direcci\u00f3n general de Judith Katalyna M\u00e9ndez Cepeda, en coordinaci\u00f3n con la Secretar\u00eda del Trabajo y Previsi\u00f3n Social, a cargo de Olga Patricia Sosa Ru\u00edz.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un gran ambiente familiar se vivi\u00f3 en esta atracci\u00f3n deportiva llevada a cabo como parte de la Semana Mundial del Skate, a la cual asistieron decenas de personas para apoyar a sus amigos y familiares, quienes participaron demostrando sus habilidades y destrezas en esta disciplina, destacando con sus mejores maniobras, trucos y deslices.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La representante de la juventud en Tamaulipas, coment\u00f3 que, \u201ces de gran valor que el gobierno apoye este tipo de iniciativas abriendo espacios para que los j\u00f3venes tengan alternativas de practicar alg\u00fan deporte, adem\u00e1s de seguir un buen camino con actividades sanas y recreativas\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Y agreg\u00f3, \u201cgenera mucha satisfacci\u00f3n colaborar con la comunidad skate y ayudar a compartir esta disciplina, que en esta ocasi\u00f3n reuni\u00f3 a j\u00f3venes de Tampico, Altamira, Reynosa, Matamoros y Ciudad Victoria en una convergencia entre el deporte y la juventud\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Finalmente dijo: \u201cseguiremos promoviendo el skateboarding como un deporte que impulsa la participaci\u00f3n de la juventud en la transformaci\u00f3n de Tamaulipas\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-1241\" src=\"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-content\/uploads\/sites\/19\/2023\/06\/img_0221.jpeg\" alt=\"\" width=\"800\" height=\"648\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-1242\" src=\"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-content\/uploads\/sites\/19\/2023\/06\/img_0263.jpg\" alt=\"\" width=\"801\" height=\"653\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atracci\u00f3n deportiva que reuni\u00f3 a j\u00f3venes de varios municipios de la entidad Junio 26 de 2023 Ciudad Victoria, Tamaulipas.- Con la intenci\u00f3n de incentivar la\u2026<\/p>\n","protected":false},"author":288,"featured_media":1240,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 03:40:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/posts\/1239"}],"collection":[{"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/users\/288"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/comments?post=1239"}],"version-history":[{"count":1,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/posts\/1239\/revisions"}],"predecessor-version":[{"id":1243,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/posts\/1239\/revisions\/1243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/media\/1240"}],"wp:attachment":[{"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/media?parent=1239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/categories?post=1239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/tags?post=1239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}