{"id":1482,"date":"2024-06-18T11:09:29","date_gmt":"2024-06-18T17:09:29","guid":{"rendered":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/?page_id=1482"},"modified":"2025-05-06T11:21:02","modified_gmt":"2025-05-06T17:21:02","slug":"documentos-normativos-y-de-seguimiento","status":"publish","type":"page","link":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/documentos-normativos-y-de-seguimiento\/","title":{"rendered":"Documentos normativos y de seguimiento"},"content":{"rendered":"<p>C\u00f3digo de Conducta del Instituto de la Juventud de Tamaulipas<\/p>\n<p><a href=\"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-content\/uploads\/sites\/19\/2025\/05\/codigo-de-conducta-del-ijt.pdf\">codigo-de-conducta-del-ijt<\/a><\/p>\n<p>Manual de Perfiles de Puestos<\/p>\n<p><a href=\"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-content\/uploads\/sites\/19\/2025\/02\/manual-de-perfiles-de-puestos.pdf\">manual-de-perfiles-de-puestos<\/a><\/p>\n<p>Manual de Procedimientos<\/p>\n<p><a href=\"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-content\/uploads\/sites\/19\/2024\/11\/manual-de-procedimientos-injuve.pdf\">manual-de-procedimientos-injuve<\/a><\/p>\n<p>Ley de los Derechos de las Personas J\u00f3venes<\/p>\n<p><a href=\"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-content\/uploads\/sites\/19\/2024\/06\/ley-de-los-derechos-de-las-personas-jovenes.pdf\">ley-de-los-derechos-de-las-personas-jovenes<\/a><\/p>\n<p>Lineamientos E144 publicados<\/p>\n<p><a href=\"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-content\/uploads\/sites\/19\/2024\/06\/lineamientos-e144-publicados.pdf\">lineamientos-e144-publicados<\/a><\/p>\n<p>Formato MIR-1718657262<\/p>\n<p><a href=\"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-content\/uploads\/sites\/19\/2024\/06\/formatomir-1718657262.pdf\">formatomir-1718657262<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u00f3digo de Conducta del Instituto de la Juventud de Tamaulipas codigo-de-conducta-del-ijt Manual de Perfiles de Puestos manual-de-perfiles-de-puestos Manual de Procedimientos manual-de-procedimientos-injuve Ley de los Derechos\u2026<\/p>\n","protected":false},"author":387,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1482","page","type-page","status-publish","hentry"],"publishpress_future_action":{"enabled":false,"date":"2026-07-21 18:41:22","action":"change-status","newStatus":"draft","terms":[],"taxonomy":""},"_links":{"self":[{"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/pages\/1482"}],"collection":[{"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/users\/387"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/comments?post=1482"}],"version-history":[{"count":6,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/pages\/1482\/revisions"}],"predecessor-version":[{"id":1697,"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/pages\/1482\/revisions\/1697"}],"wp:attachment":[{"href":"https:\/\/www.tamaulipas.gob.mx\/jovenes\/wp-json\/wp\/v2\/media?parent=1482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}