{"id":427,"date":"2024-08-08T13:19:27","date_gmt":"2024-08-08T19:19:27","guid":{"rendered":"https:\/\/www.tamaulipas.gob.mx\/energia\/?page_id=427"},"modified":"2026-05-13T10:38:32","modified_gmt":"2026-05-13T16:38:32","slug":"congreso","status":"publish","type":"page","link":"https:\/\/www.tamaulipas.gob.mx\/energia\/congreso\/","title":{"rendered":"Congreso"},"content":{"rendered":"<p><span style=\"font-size: 16px;\">El Congreso Internacional de Energ\u00eda Tamaulipas se ha consolidado como uno de los encuentros m\u00e1s importantes del sector energ\u00e9tico en M\u00e9xico, reuniendo a especialistas, empresarios, acad\u00e9micos, inversionistas y representantes gubernamentales para dialogar sobre el presente y futuro de la industria energ\u00e9tica.<\/span><\/p>\n<p><span style=\"font-size: 16px;\">Este importante foro impulsa el intercambio de ideas, la innovaci\u00f3n, la sostenibilidad y el desarrollo econ\u00f3mico de la regi\u00f3n, posicionando a Tamaulipas como un referente estrat\u00e9gico en materia energ\u00e9tica gracias a su ubicaci\u00f3n geogr\u00e1fica, infraestructura y potencial en sectores como hidrocarburos, energ\u00edas renovables y desarrollo industrial.<\/span><\/p>\n<p><span style=\"font-size: 16px;\">Tampico abrir\u00e1 nuevamente sus puertas del 27 al 29 de octubre, para recibir a expertos y asistentes de distintas partes del mundo en un evento que fortalecer\u00e1 el desarrollo energ\u00e9tico de M\u00e9xico y continuar\u00e1 impulsando el crecimiento de Tamaulipas como un polo estrat\u00e9gico para la industria.<\/span><\/p>\n<p><span style=\"font-size: 16px;\">Nos vemos en la Expo Tampico.<\/span><\/p>\n<h1><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-964\" src=\"https:\/\/www.tamaulipas.gob.mx\/energia\/wp-content\/uploads\/sites\/34\/2026\/05\/ciet-2026-poster-2.png\" alt=\"\" width=\"960\" height=\"1200\" \/><\/h1>\n<h1>Para mayor informaci\u00f3n visita:<a href=\"https:\/\/ciet.tamaulipas.gob.mx\/\"> https:\/\/ciet.tamaulipas.gob.mx\/\u00a0<\/a><\/h1>\n<hr \/>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Congreso Internacional de Energ\u00eda Tamaulipas se ha consolidado como uno de los encuentros m\u00e1s importantes del sector energ\u00e9tico en M\u00e9xico, reuniendo a especialistas, empresarios,\u2026<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-427","page","type-page","status-publish","hentry"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 14:40:37","action":"change-status","newStatus":"draft","terms":[],"taxonomy":""},"_links":{"self":[{"href":"https:\/\/www.tamaulipas.gob.mx\/energia\/wp-json\/wp\/v2\/pages\/427"}],"collection":[{"href":"https:\/\/www.tamaulipas.gob.mx\/energia\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tamaulipas.gob.mx\/energia\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tamaulipas.gob.mx\/energia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tamaulipas.gob.mx\/energia\/wp-json\/wp\/v2\/comments?post=427"}],"version-history":[{"count":21,"href":"https:\/\/www.tamaulipas.gob.mx\/energia\/wp-json\/wp\/v2\/pages\/427\/revisions"}],"predecessor-version":[{"id":965,"href":"https:\/\/www.tamaulipas.gob.mx\/energia\/wp-json\/wp\/v2\/pages\/427\/revisions\/965"}],"wp:attachment":[{"href":"https:\/\/www.tamaulipas.gob.mx\/energia\/wp-json\/wp\/v2\/media?parent=427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}